{"id":13905,"date":"2024-11-19T13:06:50","date_gmt":"2024-11-19T13:06:50","guid":{"rendered":"https:\/\/worldmusic.mus.br\/cifra\/?p=13905"},"modified":"2024-11-19T13:06:50","modified_gmt":"2024-11-19T13:06:50","slug":"vete-de-mi-caetano-veloso-world-music","status":"publish","type":"post","link":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/","title":{"rendered":"Vete de M\u00ed &#8211; Caetano Veloso &#8211; World Music"},"content":{"rendered":"<pre><b>Gm<\/b>              <b>C7<\/b>                      <b>Am7<\/b> \nTu, que llenas todo de alegr\u00eda y juventud \n            <b>Ddim<\/b>                      <b>Gm<\/b>    \nque ves fantasmas en la noche de trasluz, \n           <b>C7<\/b>                   <b>Am7<\/b> \ny oyes el canto perfumado del azul \n         <b>D7<\/b> \nvete de mi. \n \n<b>Gm<\/b>                  <b>Bbm7<\/b>         \nNo te detengas a mirar  \n                        <b>Am7<\/b>   \nlas ramas viejas del rosal \n                            <b>Ddim<\/b> \nque se marchitan sin dar flor \n<b>Gm<\/b>                    <b>Ddim<\/b> \nmira el paisaje del amor \n                        <b>Gm<\/b>     <b>C7<\/b>   <b>D7<\/b> \nque es la raz\u00f3n para so\u00f1ar y amar        \n \n<b>Gm<\/b>                <b>C7<\/b>                     <b>Am7<\/b> \nYo, que ya he luchado contra toda la maldad \n           <b>Ddim<\/b>                      <b>Gm<\/b> \ntengo las manos tan desechas de apretar \n            <b>C7<\/b> \nque no te puedo sujetar \n         <b>Cm7<\/b>    <b>F7<\/b> \nvete de mi \n \n<b>Bbmaj7<\/b>                <b>Eb7<\/b> \nSer\u00e9 en tu vida lo mejor,  \n                    <b>Am7<\/b> \nde la neblina del ayer \n                         <b>Ddim<\/b>         \ncuando me llegues a olvidar \n<b>Gm<\/b>                        <b>C7<\/b> \ncomo es mejor el verso aquel \n          <b>C#dim<\/b>      <b>F<\/b> \nque no podemos recordar.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Gm C7 Am7 Tu, que llenas todo de alegr\u00eda y juventud Ddim Gm que ves fantasmas en la noche de trasluz, C7 Am7 y oyes el canto perfumado del azul D7 vete de mi. Gm Bbm7 No te detengas a mirar Am7 las ramas viejas del rosal Ddim que se marchitan sin dar flor Gm [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13905","post","type-post","status-publish","format-standard","hentry","category-cifra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vete de M\u00ed - Caetano Veloso - World Music<\/title>\n<meta name=\"description\" content=\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vete de M\u00ed - Caetano Veloso - World Music\" \/>\n<meta property=\"og:description\" content=\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/\" \/>\n<meta property=\"og:site_name\" content=\"World Music Cifras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-19T13:06:50+00:00\" \/>\n<meta name=\"author\" content=\"xandre2007\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"xandre2007\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/\"},\"author\":{\"name\":\"xandre2007\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/person\\\/39172d294e60e05d5bb6c0fefbf2e87a\"},\"headline\":\"Vete de M\u00ed &#8211; Caetano Veloso &#8211; World Music\",\"datePublished\":\"2024-11-19T13:06:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\"},\"articleSection\":[\"Cifra\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/\",\"name\":\"Vete de M\u00ed - Caetano Veloso - World Music\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#website\"},\"datePublished\":\"2024-11-19T13:06:50+00:00\",\"description\":\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/vete-de-mi-caetano-veloso-world-music\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vete de M\u00ed &#8211; Caetano Veloso &#8211; World Music\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#website\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\",\"name\":\"World Music\",\"description\":\"Uma ampla cole\u00e7\u00e3o de cifras e tablaturas para m\u00fasicos de todos os n\u00edveis \u2013 do iniciante ao avan\u00e7ado \u2013 abrangendo diversos g\u00eaneros e estilos musicais. Nosso site \u00e9 a escolha certa para quem busca praticidade e precis\u00e3o na execu\u00e7\u00e3o de suas m\u00fasicas favoritas, com um acervo acess\u00edvel e sempre atualizado para suas pr\u00e1ticas e performances.\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\",\"name\":\"World Music\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-World-Music-Logo.png\",\"contentUrl\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-World-Music-Logo.png\",\"width\":500,\"height\":244,\"caption\":\"World Music\"},\"image\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/worldmusicescolademusicauberlandia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCj0pAbHJVz1ZCStFMBEzWIg?sub_confirmation=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/person\\\/39172d294e60e05d5bb6c0fefbf2e87a\",\"name\":\"xandre2007\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"contentUrl\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"caption\":\"xandre2007\"},\"sameAs\":[\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\"],\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/author\\\/xandre2007\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vete de M\u00ed - Caetano Veloso - World Music","description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/","og_locale":"pt_BR","og_type":"article","og_title":"Vete de M\u00ed - Caetano Veloso - World Music","og_description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","og_url":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/","og_site_name":"World Music Cifras","article_publisher":"https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/","article_published_time":"2024-11-19T13:06:50+00:00","author":"xandre2007","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"xandre2007","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/#article","isPartOf":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/"},"author":{"name":"xandre2007","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/person\/39172d294e60e05d5bb6c0fefbf2e87a"},"headline":"Vete de M\u00ed &#8211; Caetano Veloso &#8211; World Music","datePublished":"2024-11-19T13:06:50+00:00","mainEntityOfPage":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/"},"wordCount":9,"publisher":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization"},"articleSection":["Cifra"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/","url":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/","name":"Vete de M\u00ed - Caetano Veloso - World Music","isPartOf":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#website"},"datePublished":"2024-11-19T13:06:50+00:00","description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","breadcrumb":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/worldmusic.mus.br\/cifra\/vete-de-mi-caetano-veloso-world-music\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/worldmusic.mus.br\/cifra\/"},{"@type":"ListItem","position":2,"name":"Vete de M\u00ed &#8211; Caetano Veloso &#8211; World Music"}]},{"@type":"WebSite","@id":"https:\/\/worldmusic.mus.br\/cifra\/#website","url":"https:\/\/worldmusic.mus.br\/cifra\/","name":"World Music","description":"Uma ampla cole\u00e7\u00e3o de cifras e tablaturas para m\u00fasicos de todos os n\u00edveis \u2013 do iniciante ao avan\u00e7ado \u2013 abrangendo diversos g\u00eaneros e estilos musicais. Nosso site \u00e9 a escolha certa para quem busca praticidade e precis\u00e3o na execu\u00e7\u00e3o de suas m\u00fasicas favoritas, com um acervo acess\u00edvel e sempre atualizado para suas pr\u00e1ticas e performances.","publisher":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldmusic.mus.br\/cifra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization","name":"World Music","url":"https:\/\/worldmusic.mus.br\/cifra\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/logo\/image\/","url":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/uploads\/2024\/10\/cropped-World-Music-Logo.png","contentUrl":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/uploads\/2024\/10\/cropped-World-Music-Logo.png","width":500,"height":244,"caption":"World Music"},"image":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/","https:\/\/www.youtube.com\/channel\/UCj0pAbHJVz1ZCStFMBEzWIg?sub_confirmation=1"]},{"@type":"Person","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/person\/39172d294e60e05d5bb6c0fefbf2e87a","name":"xandre2007","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","url":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","contentUrl":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","caption":"xandre2007"},"sameAs":["https:\/\/worldmusic.mus.br\/cifra"],"url":"https:\/\/worldmusic.mus.br\/cifra\/author\/xandre2007\/"}]}},"_links":{"self":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/13905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/comments?post=13905"}],"version-history":[{"count":1,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/13905\/revisions"}],"predecessor-version":[{"id":13906,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/13905\/revisions\/13906"}],"wp:attachment":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/media?parent=13905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/categories?post=13905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/tags?post=13905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}