{"id":7876,"date":"2024-10-20T18:07:04","date_gmt":"2024-10-20T18:07:04","guid":{"rendered":"https:\/\/worldmusic.mus.br\/cifra\/?p=7876"},"modified":"2024-10-20T18:07:04","modified_gmt":"2024-10-20T18:07:04","slug":"enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada","status":"publish","type":"post","link":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/","title":{"rendered":"Enquanto Eu Brindo C\u00ea Chora &#8211; Bruno e Marrone &#8211; Cifra Simplificada"},"content":{"rendered":"<pre>Intro:  <b>G<\/b>\n                         <b>F<\/b>\n<span class=\"tablatura\"><span class=\"cnt\">E|-----------------------1----------|\nB|-----------------------1----------|\nG|-5\/7--7\/9--------------2----------|\nD|-----------------------3----------|\nA|-----------------------3----------|\nE|-----------------------1----------|<\/span><\/span>\n  \n\n\n     <b>C9<\/b>\nPois \u00e9\n                                                  <b>Em<\/b>\nMas que surpresa cruzar com voc\u00ea depois de tanto tempo\n                                                   <b>Am<\/b>    (<b>Am<\/b> <b>G<\/b>)\nNa mesa ao lado, sentada, sozinha sei que est\u00e1 me vendo\n             <b>F<\/b>                      <b>Fm<\/b>\nO mais engra\u00e7ado foi ver sua cara\n\n          <b>C9<\/b>\nTentando n\u00e3o chorar\n                                               <b>G<\/b>\nDesesperou quando percebeu algu\u00e9m aqui no seu lugar\n                                               <b>Dm<\/b>\nPegou telefone, fingiu estar falando, s\u00f3 pra disfar\u00e7ar\n                                   <b>F<\/b>       <b>G<\/b>\nBebendo assim desse jeito s\u00f3 vai piorar\n\n\nRefr\u00e3o (2x):                   \n                        <b>C9<\/b>\nEnquanto eu brindo c\u00ea chora\n                                          <b>G<\/b>\nPorque n\u00e3o levanta da mesa, tem t\u00e1xi l\u00e1 fora\n                                  <b>Dm<\/b>\nVoc\u00ea se achava perfeita, insubstitu\u00edvel\n                                         <b>F<\/b>     <b>G<\/b>\nTe ver desse jeito chorando era t\u00e3o previs\u00edvel\n                          \n                        <b>C9<\/b>\nEnquanto eu brindo c\u00ea chora\n\n(<b>C<\/b> <b>G<\/b> <b>Dm<\/b> <b>F<\/b> <b>G<\/b>)\n\n          <b>C9<\/b>\nTentando n\u00e3o chorar\n                                               <b>G<\/b>\nDesesperou quando percebeu algu\u00e9m aqui no seu lugar\n                                               <b>Dm<\/b>\nPegou telefone, fingiu estar falando, s\u00f3 pra disfar\u00e7ar\n                                   <b>F<\/b>       <b>G<\/b>\nBebendo assim desse jeito s\u00f3 vai piorar\n\n\nRefr\u00e3o (2x):                   \n                        <b>C9<\/b>\nEnquanto eu brindo c\u00ea chora\n                                          <b>G<\/b>\nPorque n\u00e3o levanta da mesa, tem t\u00e1xi l\u00e1 fora\n                                  <b>Dm<\/b>\nVoc\u00ea se achava perfeita, insubstitu\u00edvel\n                                         <b>F<\/b>     <b>G<\/b>\nTe ver desse jeito chorando era t\u00e3o previs\u00edvel\n                          \n                        <b>C9<\/b>\nEnquanto eu brindo c\u00ea chora<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Intro: G F E|&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;1&#8212;&#8212;&#8212;-| B|&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;1&#8212;&#8212;&#8212;-| G|-5\/7&#8211;7\/9&#8212;&#8212;&#8212;&#8212;&#8211;2&#8212;&#8212;&#8212;-| D|&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;3&#8212;&#8212;&#8212;-| A|&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;3&#8212;&#8212;&#8212;-| E|&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;1&#8212;&#8212;&#8212;-| C9 Pois \u00e9 Em Mas que surpresa cruzar com voc\u00ea depois de tanto tempo Am (Am G) Na mesa ao lado, sentada, sozinha sei que est\u00e1 me vendo F Fm O mais engra\u00e7ado foi ver sua cara C9 Tentando n\u00e3o chorar G Desesperou quando percebeu algu\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7876","post","type-post","status-publish","format-standard","hentry","category-cifra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada<\/title>\n<meta name=\"description\" content=\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada\" \/>\n<meta property=\"og:description\" content=\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/\" \/>\n<meta property=\"og:site_name\" content=\"World Music Cifras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-20T18:07:04+00:00\" \/>\n<meta name=\"author\" content=\"xandre2007\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"xandre2007\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/\"},\"author\":{\"name\":\"xandre2007\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/person\\\/39172d294e60e05d5bb6c0fefbf2e87a\"},\"headline\":\"Enquanto Eu Brindo C\u00ea Chora &#8211; Bruno e Marrone &#8211; Cifra Simplificada\",\"datePublished\":\"2024-10-20T18:07:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\"},\"articleSection\":[\"Cifra\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/\",\"name\":\"Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#website\"},\"datePublished\":\"2024-10-20T18:07:04+00:00\",\"description\":\"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enquanto Eu Brindo C\u00ea Chora &#8211; Bruno e Marrone &#8211; Cifra Simplificada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#website\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\",\"name\":\"World Music\",\"description\":\"Uma ampla cole\u00e7\u00e3o de cifras e tablaturas para m\u00fasicos de todos os n\u00edveis \u2013 do iniciante ao avan\u00e7ado \u2013 abrangendo diversos g\u00eaneros e estilos musicais. Nosso site \u00e9 a escolha certa para quem busca praticidade e precis\u00e3o na execu\u00e7\u00e3o de suas m\u00fasicas favoritas, com um acervo acess\u00edvel e sempre atualizado para suas pr\u00e1ticas e performances.\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#organization\",\"name\":\"World Music\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-World-Music-Logo.png\",\"contentUrl\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-World-Music-Logo.png\",\"width\":500,\"height\":244,\"caption\":\"World Music\"},\"image\":{\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/worldmusicescolademusicauberlandia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCj0pAbHJVz1ZCStFMBEzWIg?sub_confirmation=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/#\\\/schema\\\/person\\\/39172d294e60e05d5bb6c0fefbf2e87a\",\"name\":\"xandre2007\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"contentUrl\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/wp-content\\\/litespeed\\\/avatar\\\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659\",\"caption\":\"xandre2007\"},\"sameAs\":[\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\"],\"url\":\"https:\\\/\\\/worldmusic.mus.br\\\/cifra\\\/author\\\/xandre2007\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada","description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/","og_locale":"pt_BR","og_type":"article","og_title":"Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada","og_description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","og_url":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/","og_site_name":"World Music Cifras","article_publisher":"https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/","article_published_time":"2024-10-20T18:07:04+00:00","author":"xandre2007","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"xandre2007","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/#article","isPartOf":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/"},"author":{"name":"xandre2007","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/person\/39172d294e60e05d5bb6c0fefbf2e87a"},"headline":"Enquanto Eu Brindo C\u00ea Chora &#8211; Bruno e Marrone &#8211; Cifra Simplificada","datePublished":"2024-10-20T18:07:04+00:00","mainEntityOfPage":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/"},"wordCount":12,"publisher":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization"},"articleSection":["Cifra"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/","url":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/","name":"Enquanto Eu Brindo C\u00ea Chora - Bruno e Marrone - Cifra Simplificada","isPartOf":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#website"},"datePublished":"2024-10-20T18:07:04+00:00","description":"Cifras f\u00e1ceis, completas e precisas para voc\u00ea tocar qualquer m\u00fasica! Explore nosso acervo e aprimore seu talento!","breadcrumb":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/worldmusic.mus.br\/cifra\/enquanto-eu-brindo-ce-chora-bruno-e-marrone-cifra-simplificada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/worldmusic.mus.br\/cifra\/"},{"@type":"ListItem","position":2,"name":"Enquanto Eu Brindo C\u00ea Chora &#8211; Bruno e Marrone &#8211; Cifra Simplificada"}]},{"@type":"WebSite","@id":"https:\/\/worldmusic.mus.br\/cifra\/#website","url":"https:\/\/worldmusic.mus.br\/cifra\/","name":"World Music","description":"Uma ampla cole\u00e7\u00e3o de cifras e tablaturas para m\u00fasicos de todos os n\u00edveis \u2013 do iniciante ao avan\u00e7ado \u2013 abrangendo diversos g\u00eaneros e estilos musicais. Nosso site \u00e9 a escolha certa para quem busca praticidade e precis\u00e3o na execu\u00e7\u00e3o de suas m\u00fasicas favoritas, com um acervo acess\u00edvel e sempre atualizado para suas pr\u00e1ticas e performances.","publisher":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldmusic.mus.br\/cifra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/worldmusic.mus.br\/cifra\/#organization","name":"World Music","url":"https:\/\/worldmusic.mus.br\/cifra\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/logo\/image\/","url":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/uploads\/2024\/10\/cropped-World-Music-Logo.png","contentUrl":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/uploads\/2024\/10\/cropped-World-Music-Logo.png","width":500,"height":244,"caption":"World Music"},"image":{"@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/worldmusicescolademusicauberlandia\/","https:\/\/www.youtube.com\/channel\/UCj0pAbHJVz1ZCStFMBEzWIg?sub_confirmation=1"]},{"@type":"Person","@id":"https:\/\/worldmusic.mus.br\/cifra\/#\/schema\/person\/39172d294e60e05d5bb6c0fefbf2e87a","name":"xandre2007","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","url":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","contentUrl":"https:\/\/worldmusic.mus.br\/cifra\/wp-content\/litespeed\/avatar\/7afb8c6d80555b9330d0a98f54fe1aa0.jpg?ver=1778344659","caption":"xandre2007"},"sameAs":["https:\/\/worldmusic.mus.br\/cifra"],"url":"https:\/\/worldmusic.mus.br\/cifra\/author\/xandre2007\/"}]}},"_links":{"self":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/7876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/comments?post=7876"}],"version-history":[{"count":1,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/7876\/revisions"}],"predecessor-version":[{"id":7877,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/posts\/7876\/revisions\/7877"}],"wp:attachment":[{"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/media?parent=7876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/categories?post=7876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldmusic.mus.br\/cifra\/wp-json\/wp\/v2\/tags?post=7876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}